{"id":7452,"date":"2019-06-26T00:23:59","date_gmt":"2019-06-25T22:23:59","guid":{"rendered":"https:\/\/wncri.org\/frdev\/?p=7452"},"modified":"2019-07-01T17:16:24","modified_gmt":"2019-07-01T15:16:24","slug":"larrestation-violente-dune-jeune-femme-en-iran-provoque-un-tolle","status":"publish","type":"post","link":"https:\/\/wncri.org\/fr\/2019\/06\/26\/larrestation-violente-dune-jeune-femme-en-iran-provoque-un-tolle\/","title":{"rendered":"L&#8217;arrestation violente d&#8217;une jeune femme en Iran provoque un toll\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">CNRI Femmes &#8211; L&#8217;arrestation\nviolente d&#8217;une jeune femme \u00e0 T\u00e9h\u00e9ran a provoqu\u00e9 un toll\u00e9 en Iran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des agents en civil des Forces\nde s\u00e9curit\u00e9 ont arr\u00eat\u00e9 cinq jeunes femmes et hommes dans un parc de Tehranpars o\u00f9\nils jouaient avec des pistolets \u00e0 eau, le samedi 22 juin 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un clip vid\u00e9o post\u00e9 sur les\nm\u00e9dias sociaux montre un agent en civil s&#8217;emparant d&#8217;une jeune fille de 15-16\nans, et la poussant violemment dans la voiture de police. Le conducteur de la\nvoiture de police et tous les autres agents des environs portaient des\nv\u00eatements civils, selon la d\u00e9p\u00eache de l&#8217;agence Fars dat\u00e9e du 24 juin 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon des t\u00e9moins oculaires,\nles jeunes jouaient au pistolet \u00e0 eau dans le parc. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"750\" height=\"430\" data-src=\"https:\/\/wncri.org\/fr\/\/wp-content\/uploads\/2019\/07\/girl-in-the-park-2.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"arrestation violente\" class=\"wp-image-7483 lazyload\"\/><noscript><img decoding=\"async\" width=\"750\" height=\"430\" src=\"https:\/\/wncri.org\/fr\/\/wp-content\/uploads\/2019\/07\/girl-in-the-park-2.jpg\" alt=\"arrestation violente\" class=\"wp-image-7483\" srcset=\"https:\/\/wncri.org\/fr\/wp-content\/uploads\/2019\/07\/girl-in-the-park-2.jpg 750w, https:\/\/wncri.org\/fr\/wp-content\/uploads\/2019\/07\/girl-in-the-park-2-300x172.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/noscript><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le 24 juin, le chef de la\npolice de T\u00e9h\u00e9ran Hossein Rahimi a d\u00e9clar\u00e9 \u00e0 la presse \u00e0 propos de\nl&#8217;arrestation de cinq jeunes femmes et jeunes hommes : \u00ab&nbsp;Ils sont accus\u00e9s\nd\u2019avoir refus\u00e9 d\u2019obtemp\u00e9rer aux ordres de la police, d\u2019avoir enfreint les\nnormes sociales, de s&#8217;\u00eatre oppos\u00e9 aux agents de police et d\u2019avoir enlev\u00e9 leur\nvoile. Ils sont toujours en garde \u00e0 vue.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette arrestation violente a soulev\u00e9 une vague d&#8217;indignation dans la soci\u00e9t\u00e9. M\u00eame une agence de presse officielle a cit\u00e9 un sociologue qui a d\u00e9clar\u00e9 : \u00ab&nbsp;Ce type de <a href=\"https:\/\/wncri.org\/fr\/\/2019\/06\/02\/le-voile-obligatoire-et-les-restrictions-imposees-aux-femmes-sont-vitaux-pour-les-mollahs\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">comportement<\/a> n&#8217;est ni punitif, ni humanitaire, ni islamique. Nous avons des lois. La loi ne permet \u00e0 personne d&#8217;agir comme bon lui semble. En m\u00eame temps, nous avons des polici\u00e8res. Dans de tels cas, concernant des femmes, ce sont des polici\u00e8res qui doivent intervenir.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9action au toll\u00e9 g\u00e9n\u00e9ral\ncontre cette arrestation violente, le commandant des Forces de s\u00e9curit\u00e9 de\nT\u00e9h\u00e9ran a ordonn\u00e9, quelques heures apr\u00e8s l&#8217;annonce de cette nouvelle, le renvoi\net la d\u00e9tention des deux agents de police directement impliqu\u00e9s. Cependant, le\n25 juin 2019, il a retir\u00e9 son ordre et l&#8217;a report\u00e9 \u00e0 la \u00ab&nbsp;conclusion de l\u2019enqu\u00eate&nbsp;\u00bb.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" data-src=\"https:\/\/wncri.org\/fr\/\/wp-content\/uploads\/2019\/07\/metro1.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"arrestation violente\" class=\"wp-image-7487 lazyload\" width=\"317\" height=\"207\"\/><noscript><img decoding=\"async\" src=\"https:\/\/wncri.org\/fr\/\/wp-content\/uploads\/2019\/07\/metro1.jpg\" alt=\"arrestation violente\" class=\"wp-image-7487\" width=\"317\" height=\"207\"><\/noscript><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le m\u00eame ordre d&#8217;id\u00e9es, un\nautre clip vid\u00e9o publi\u00e9 dans les m\u00e9dias sociaux montrait une jeune femme battue\npar les forces de s\u00e9curit\u00e9 dans une station de m\u00e9tro \u00e0 T\u00e9h\u00e9ran pour \u00eatre jug\u00e9e\nmal-voil\u00e9e. La jeune femme pleure et dit que des agents de police l&#8217;ont frapp\u00e9e\net jet\u00e9e \u00e0 terre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il a \u00e9galement \u00e9t\u00e9 signal\u00e9 que le r\u00e9gime a l\u2019intention de faire stationner des <a href=\"https:\/\/wncri.org\/fr\/\/2019\/06\/07\/2000-nouvelles-unites-pour-verbaliser-les-femmes-mal-voilees-en-iran\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">patrouilles<\/a> dans les zones de loisirs dans les jours \u00e0 venir pour surveiller le respect par les femmes du port obligatoire du voile et leur donner des avertissements. (Agence ISNA &#8211; 24 juin 2019)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CNRI Femmes &#8211; L&#8217;arrestation violente d&#8217;une jeune femme \u00e0 T\u00e9h\u00e9ran a provoqu\u00e9 un toll\u00e9 en Iran. Des agents en civil des Forces de s\u00e9curit\u00e9 ont arr\u00eat\u00e9 cinq jeunes femmes et hommes dans un parc de Tehranpars o\u00f9 ils jouaient avec des pistolets \u00e0 eau, le samedi 22 juin 2019. Un clip vid\u00e9o post\u00e9 sur les [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[3],"tags":[],"class_list":["post-7452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos-des-femmes"],"_links":{"self":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts\/7452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/comments?post=7452"}],"version-history":[{"count":0,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts\/7452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/media\/7484"}],"wp:attachment":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/media?parent=7452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/categories?post=7452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/tags?post=7452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}