{"id":26259,"date":"2026-05-13T11:05:17","date_gmt":"2026-05-13T09:05:17","guid":{"rendered":"https:\/\/wncri.org\/fr\/?p=26259"},"modified":"2026-05-13T11:05:18","modified_gmt":"2026-05-13T09:05:18","slug":"campagne-non-aux-executions-du-mardi-3","status":"publish","type":"post","link":"https:\/\/wncri.org\/fr\/2026\/05\/13\/campagne-non-aux-executions-du-mardi-3\/","title":{"rendered":"120e semaine de la campagne \u00ab Non aux ex\u00e9cutions du mardi \u00bb : pression continue sur les prisonni\u00e8res politiques en Iran"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Pour la 120e semaine cons\u00e9cutive de la <a href=\"https:\/\/wncri.org\/fr\/2026\/05\/05\/non-aux-executions-du-mardi-6\/\" target=\"_blank\" rel=\"noreferrer noopener\">campagne \u00ab Non aux ex\u00e9cutions du mardi \u00bb<\/a>, des prisonniers politiques dans 56 \u00e9tablissements p\u00e9nitentiaires d\u2019Iran ont de nouveau lanc\u00e9 une gr\u00e8ve de la faim, le mardi 12 mai 2026, en d\u00e9pit de l\u2019intensification de la pression s\u00e9curitaire et du durcissement des restrictions. La poursuite de ces protestations intervient alors que les autorit\u00e9s carc\u00e9rales ont tent\u00e9, ces derni\u00e8res semaines, de mettre un terme \u00e0 la participation des d\u00e9tenus, et plus particuli\u00e8rement \u00e0 celle des prisonni\u00e8res politiques, par le biais de menaces, de sanctions disciplinaires et de mesures restrictives accrues.<\/h4>\n\n\n\n<p>Des informations \u00e9manant de la <a href=\"https:\/\/wncri.org\/fr\/2026\/04\/25\/pression-accrue-prisonnieres-devin\/\" target=\"_blank\" rel=\"noreferrer noopener\">prison d\u2019Evin<\/a> indiquent que la pression sur les prisonni\u00e8res politiques s\u2019est consid\u00e9rablement accentu\u00e9e. Selon ces sources, Zahra Safaei, Forough Taghipour, Marzieh Farsi, Elaheh Fooladi, Arghavan Fallahi, Shiva Esmaeili et Golrokh Iraee, qui avaient d\u00e9j\u00e0 \u00e9t\u00e9 priv\u00e9es de visites familiales pendant trois semaines pour leur participation au mouvement, ont \u00e9t\u00e9 frapp\u00e9es d\u2019une nouvelle interdiction de visite de trois semaines apr\u00e8s avoir de nouveau pris part aux protestations.<\/p>\n\n\n\n<p>Parall\u00e8lement, des dizaines d\u2019autres prisonniers auraient fait l\u2019objet de mesures disciplinaires et de nouvelles restrictions au seul motif qu\u2019ils se trouvaient dans la cour de la prison ou qu\u2019ils ont \u00e9t\u00e9 t\u00e9moins des rassemblements de protestation des d\u00e9tenus.<\/p>\n\n\n\n<p>Une partie du dernier communiqu\u00e9 publi\u00e9 par la campagne \u00ab Non aux ex\u00e9cutions du mardi \u00bb \u00e9voque le climat s\u00e9curitaire renforc\u00e9 \u00e0 la suite du d\u00e9clenchement de la guerre, affirmant que le r\u00e9gime iranien a intensifi\u00e9 sa r\u00e9pression contre la soci\u00e9t\u00e9 et la dissidence politique sous couvert de l\u2019\u00e9tat de guerre. Le texte souligne par ailleurs qu\u2019au moins 23 prisonniers politiques ou poursuivis pour des motifs de s\u00e9curit\u00e9 ont \u00e9t\u00e9 ex\u00e9cut\u00e9s depuis le d\u00e9but de l\u2019ann\u00e9e iranienne 1405.<\/p>\n\n\n\n<p>Le communiqu\u00e9 met \u00e9galement en lumi\u00e8re la pression constante exerc\u00e9e sur les familles des supplici\u00e9s, notant que, m\u00eame apr\u00e8s 40 jours, les d\u00e9pouilles de plusieurs <a href=\"https:\/\/fr.ncr-iran.org\/actualites\/droits-humains-2\/la-machine-a-tuer-iranienne-execute-dix-prisonniers-politiques-en-seize-jours\/\" target=\"_blank\" rel=\"noreferrer noopener\">prisonniers politiques ex\u00e9cut\u00e9s,<\/a> dont Vahid Bani Amerian, Pouya Ghobadi, Babak Alipour, Akbar (Shahrokh) Daneshvar Kar, Mohammad Taghavi et Abolhassan Montazer, n\u2019ont toujours pas \u00e9t\u00e9 restitu\u00e9es \u00e0 leurs proches.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour la 120e semaine cons\u00e9cutive de la campagne \u00ab Non aux ex\u00e9cutions du mardi \u00bb, des prisonniers politiques dans 56 \u00e9tablissements p\u00e9nitentiaires d\u2019Iran ont de nouveau lanc\u00e9 une gr\u00e8ve de la faim, le mardi 12 mai 2026, en d\u00e9pit de l\u2019intensification de la pression s\u00e9curitaire et du durcissement des restrictions. La poursuite de ces protestations [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":26260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[3],"tags":[369,370],"class_list":["post-26259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos-des-femmes","tag-manifestations","tag-prisonnieres"],"_links":{"self":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts\/26259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/comments?post=26259"}],"version-history":[{"count":1,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts\/26259\/revisions"}],"predecessor-version":[{"id":26261,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts\/26259\/revisions\/26261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/media\/26260"}],"wp:attachment":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/media?parent=26259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/categories?post=26259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/tags?post=26259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}