{"id":26256,"date":"2026-05-12T14:39:33","date_gmt":"2026-05-12T12:39:33","guid":{"rendered":"https:\/\/wncri.org\/fr\/?p=26256"},"modified":"2026-05-12T14:39:35","modified_gmt":"2026-05-12T12:39:35","slug":"la-prisonniere-politique-maryam-derisi","status":"publish","type":"post","link":"https:\/\/wncri.org\/fr\/2026\/05\/12\/la-prisonniere-politique-maryam-derisi\/","title":{"rendered":"Une prisonni\u00e8re politique de nouveau condamn\u00e9e \u00e0 la prison par le r\u00e9gime iranien"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Maryam Derisi, prisonni\u00e8re politique originaire de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Kazeroun\" target=\"_blank\" rel=\"noreferrer noopener\">Kazeroun<\/a>, a de nouveau \u00e9t\u00e9 condamn\u00e9e \u00e0 une peine de prison dans le cadre de la r\u00e9pression judiciaire et s\u00e9curitaire exerc\u00e9e par le gouvernement iranien contre les dissidents.<\/h4>\n\n\n\n<p>Dans une nouvelle affaire, une chambre du tribunal r\u00e9volutionnaire de Chiraz l&#8217;a condamn\u00e9e \u00e0 un an et trois mois d&#8217;emprisonnement ferme pour \u00ab propagande contre l&#8217;\u00c9tat \u00bb. Le verdict a \u00e9t\u00e9 officiellement communiqu\u00e9 \u00e0 son avocat. Mme Derisi avait d\u00e9j\u00e0 \u00e9t\u00e9 condamn\u00e9e dans une autre affaire par le tribunal correctionnel de Kazeroun \u00e0 un an de prison et 74 coups de fouet pour \u00ab trouble \u00e0 l&#8217;ordre public \u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qui est Maryam Derisi ?<\/strong><\/h3>\n\n\n\n<p>\u00c9tudiante en master d&#8217;anglais \u00e0 l&#8217;universit\u00e9 de Saveh, Maryam Derisi a \u00e9t\u00e9 la cible r\u00e9p\u00e9t\u00e9e des services de s\u00e9curit\u00e9 du r\u00e9gime iranien ces derni\u00e8res ann\u00e9es, faisant l&#8217;objet de plusieurs arrestations et poursuites judiciaires.<\/p>\n\n\n\n<p>Sa derni\u00e8re interpellation remonte au 14 f\u00e9vrier 2026, date \u00e0 laquelle <a href=\"https:\/\/wncri.org\/fr\/2023\/01\/27\/maryam-derisi\/\" target=\"_blank\" rel=\"noreferrer noopener\">elle a \u00e9t\u00e9 arr\u00eat\u00e9e<\/a> par des agents du minist\u00e8re du Renseignement. Elle avait \u00e9galement \u00e9t\u00e9 arr\u00eat\u00e9e lors des manifestations nationales du 15 octobre 2022. Apr\u00e8s pr\u00e8s de trois semaines de d\u00e9tention, elle avait \u00e9t\u00e9 lib\u00e9r\u00e9e sous caution le 2 novembre de la m\u00eame ann\u00e9e. Toutefois, les poursuites judiciaires \u00e0 son encontre se sont poursuivies et, quelques mois plus tard, elle a \u00e9t\u00e9 condamn\u00e9e dans cette m\u00eame affaire \u00e0 22 mois et 17 jours de prison.<\/p>\n\n\n\n<p>Une fois la sentence confirm\u00e9e, Maryam Derisi a \u00e9t\u00e9 convoqu\u00e9e le 4 ao\u00fbt 2024 pour commencer \u00e0 purger sa peine et a \u00e9t\u00e9 transf\u00e9r\u00e9e \u00e0 la prison d&#8217;Adelabad, \u00e0 Chiraz.<\/p>\n\n\n\n<p>D\u00e9but janvier 2025, sa peine a \u00e9t\u00e9 convertie en un r\u00e9gime de semi-libert\u00e9, permettant sa sortie temporaire. Cependant, cette mesure a \u00e9t\u00e9 de courte dur\u00e9e. Le 1er mars 2025, face \u00e0 l&#8217;opposition du procureur et des autorit\u00e9s de s\u00e9curit\u00e9 impliqu\u00e9es dans son dossier, la militante politique a \u00e9t\u00e9 r\u00e9int\u00e9gr\u00e9e \u00e0 <a href=\"https:\/\/wncri.org\/fr\/2021\/12\/10\/les-conditions-des-femmes-prisons\/\" target=\"_blank\" rel=\"noreferrer noopener\">la prison d&#8217;Adelabad, \u00e0 Chiraz<\/a>, pour poursuivre l&#8217;ex\u00e9cution de sa peine.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maryam Derisi, prisonni\u00e8re politique originaire de Kazeroun, a de nouveau \u00e9t\u00e9 condamn\u00e9e \u00e0 une peine de prison dans le cadre de la r\u00e9pression judiciaire et s\u00e9curitaire exerc\u00e9e par le gouvernement iranien contre les dissidents. Dans une nouvelle affaire, une chambre du tribunal r\u00e9volutionnaire de Chiraz l&#8217;a condamn\u00e9e \u00e0 un an et trois mois d&#8217;emprisonnement ferme [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":26257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[3],"tags":[370],"class_list":["post-26256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infos-des-femmes","tag-prisonnieres"],"_links":{"self":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts\/26256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/comments?post=26256"}],"version-history":[{"count":1,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts\/26256\/revisions"}],"predecessor-version":[{"id":26258,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/posts\/26256\/revisions\/26258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/media\/26257"}],"wp:attachment":[{"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/media?parent=26256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/categories?post=26256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wncri.org\/fr\/wp-json\/wp\/v2\/tags?post=26256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}